{"id":3400,"date":"2018-09-11T14:24:28","date_gmt":"2018-09-11T12:24:28","guid":{"rendered":"https:\/\/www.zurbrueggen.de\/magazin\/?p=3400"},"modified":"2018-09-12T15:15:11","modified_gmt":"2018-09-12T13:15:11","slug":"das-ergonomische-buero-zu-hause","status":"publish","type":"post","link":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/","title":{"rendered":"Das ergonomische B\u00fcro zu Hause"},"content":{"rendered":"<p id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-MitgeeignetenB\u00fcrom\u00f6belndenArbeitsplatzergonomischgestalten\"><span class=\"vorschau\" style=\"font-family: 'Roboto Slab'; font-size: 22px; line-height: 34px; font-weight: 300; margin-top: 40px;\">Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch arbeiten, sind Ihnen R\u00fccken- und Nackenschmerzen wahrscheinlich vertraut. Mit ergonomischen B\u00fcrom\u00f6beln wirken Sie dem entgegen und nutzen den Raum mithilfe praktischer Funktionen auch noch optimal aus. Dank der gro\u00dfen Auswahl an M\u00f6beln und mit den folgenden Tipps ist die Einrichtung Ihres Arbeitsplatzes nach den Prinzipien der Ergonomie schnell umgesetzt. Ihr R\u00fccken wird es Ihnen daf\u00fcr lange danken.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><!--more--><\/p>\n<h2><\/h2>\n<h2><\/h2>\n<h2 id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-DasergonomischeB\u00fcro:gesundesArbeitenamSchreibtisch\"><span class=\"fliesstext subheading\" style=\"font-family: 'Roboto Slab', sans-serif; font-size: 20px; line-height: 24px; font-weight: 400; margin-top: 40px; text-transform: none; margin-left: 12.5%;\">Das ergonomische B\u00fcro: gesundes Arbeiten am Schreibtisch<\/span><\/h2>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Seit einigen Jahren setzt sich die Erkenntnis durch, dass das ergonomische B\u00fcro f\u00fcr die Gesundheit, Produktivit\u00e4t und Motivation der Mitarbeiter in Unternehmen unverzichtbar ist. Dies gilt f\u00fcr den Arbeitsplatz in der Firma genauso wie f\u00fcr Ihre Schreibtischt\u00e4tigkeiten zu Hause. Anders gesagt: Chefsessel statt Designerholzstuhl im Vintage-Look.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3424\" aria-describedby=\"caption-attachment-3424\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3424 size-full\" src=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template.jpg\" alt=\"Nowy-Styl - 4ME &amp; 2ME-chairs\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template.jpg 1200w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template-300x169.jpg 300w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template-768x432.jpg 768w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template-1024x576.jpg 1024w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template-665x374.jpg 665w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-template-462x260.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-3424\" class=\"wp-caption-text\">Nowy-Styl &#8211; 4ME &amp; 2ME-chairs<\/figcaption><\/figure>\n<h2><\/h2>\n<h2 id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-Ergonomie:dieWissenschaftvomrichtigenArbeiten\"><span class=\"fliesstext subheading\" style=\"font-family: 'Roboto Slab', sans-serif; font-size: 20px; line-height: 24px; font-weight: 400; margin-top: 40px; text-transform: none; margin-left: 12.5%;\">Ergonomie: die Wissenschaft vom richtigen Arbeiten<\/span><\/h2>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Was wie ein Buzzword der modernen Leistungsgesellschaft klingt, wurde bereits 1857 von Wojciech Jastrzebowski im Rahmen der Industrialisierung definiert: Als Ergonomie bezeichnete er die Wissenschaft, einen optimalen Arbeitsplatz und ideale Arbeitsbedingungen zu schaffen. \u00dcbertragen auf die heutige B\u00fcrot\u00e4tigkeit bedeutet dies: Das ergonomische B\u00fcro erlaubt es dem Menschen, m\u00f6glichst lange Zeit ohne k\u00f6rperliche Beschwerden produktiv am Schreibtisch zu arbeiten und dabei nicht zu erm\u00fcden. Das Recht auf einen entsprechend gestalteten Arbeitsplatz\u00a0<a class=\"external-link\" href=\"https:\/\/www.gesetze-im-internet.de\/arbschg\/\" rel=\"nofollow\">wurde mittlerweile im Arbeitsschutzgesetz verankert<\/a>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3418\" aria-describedby=\"caption-attachment-3418\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3418 size-full\" src=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03.jpg\" alt=\"roehr-object-plus\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03.jpg 1200w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03-300x169.jpg 300w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03-768x432.jpg 768w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03-1024x576.jpg 1024w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03-665x374.jpg 665w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-roehr-object-plus-52426-xx-m-03-462x260.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-3418\" class=\"wp-caption-text\">r\u00f6hr &#8211; object-plus<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2 id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-WiesiehtdasergonomischeB\u00fcroaus?\"><span class=\"fliesstext subheading\" style=\"font-family: 'Roboto Slab', sans-serif; font-size: 20px; line-height: 24px; font-weight: 400; margin-top: 40px; text-transform: none; margin-left: 12.5%;\">Wie sieht das ergonomische B\u00fcro aus?<\/span><\/h2>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Auf Instagram sieht der schnuckelige kleine Arbeitsplatz zu Hause mit wei\u00dfem Tischchen und\u00a0<a class=\"external-link\" href=\"https:\/\/www.zurbrueggen.de\/magazin\/stuehle-dekorative-und-bequeme-sitzgelegenheiten-fuer-jeden-tag\/\" rel=\"nofollow\">wei\u00dfem Holzstuhl<\/a>\u00a0zwar herrlich dekorativ aus, doch in der Realit\u00e4t w\u00fcrde Ihr R\u00fccken sp\u00e4testens nach zwei Tagen in den Streik treten. Die Grundlagen f\u00fcr ein produktives, beschwerdefreies Arbeiten sind ein guter Schreibtisch und ein hochwertiger Schreibtischstuhl.<\/span><\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">F\u00fcr den Schreibtisch gelten folgende Regeln:<\/span><\/p>\n<ul>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Die Mindestma\u00dfe betragen 80 x 160 cm.<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Die H\u00f6he \u00fcbertrifft die Sitzfl\u00e4che um 20 bis 30 cm.<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Die Unterarme k\u00f6nnen horizontal auf der Tischfl\u00e4che aufliegen.<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Die Handballenauflage vor dem Tastenfeld betr\u00e4gt zwischen 5 und 10 cm.<\/span><\/li>\n<\/ul>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Ideal sind h\u00f6henverstellbare Schreibtische, die Sie individuell an Ihre Bed\u00fcrfnisse anpassen k\u00f6nnen. Viele Modelle bieten die M\u00f6glichkeit, sie per Knopfdruck in ein Stehpult zu verwandeln. So k\u00f6nnen Sie abwechselnd im Sitzen und Stehen arbeiten \u2013 das erfrischt den Geist und entlastet den R\u00fccken.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3421\" aria-describedby=\"caption-attachment-3421\" style=\"width: 1200px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3421 size-full\" src=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04.jpg\" alt=\"StepOne -Komplett-B\u00fcro\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04.jpg 1200w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04-300x169.jpg 300w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04-768x432.jpg 768w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04-1024x576.jpg 1024w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04-665x374.jpg 665w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-step-one-1117xxx-m-04-462x260.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-3421\" class=\"wp-caption-text\">StepOne -Komplett-B\u00fcro<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">F\u00fcr den Schreibtischstuhl gilt:<\/span><\/p>\n<ul>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Er l\u00e4sst sich in der H\u00f6he verstellen.<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Die Beine bilden einen rechten Winkel (90 Grad).<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Zwischen Kniekehlen und Sitzfl\u00e4che sind einige Zentimeter Platz.<\/span><\/li>\n<li><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Zwischen Oberschenkeln und Schreibtischplatte sind ebenfalls einige Zentimeter frei.<\/span><\/li>\n<\/ul>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Daneben gibt es noch diverse weitere Kriterien, \u00fcber die Sie nachdenken sollten: M\u00f6chten Sie in einem \u00fcppigen Chefsessel aus Leder sitzen oder lieber auf einem leichten Schreibtischstuhl mit einer Lehne aus luftdurchl\u00e4ssigem Mesh-Gewebe, sodass Sie im Sommer nicht schwitzen? Wollen Sie sich an einer Kopfst\u00fctze zur\u00fccklehnen k\u00f6nnen oder mit einem zus\u00e4tzlichen Polster den empfindlichen Lendenbereich st\u00fctzen?<\/span><\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Ein letzter Tipp zum Schreibtischstuhl: Wenn Sie einen teuren Teppichboden vor den Rollen des Drehstuhls sch\u00fctzen m\u00f6chten, legen Sie im Arbeitsbereich Ihres Wohnzimmers eine spezielle Bodenschutzmatte darunter.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3425\" aria-describedby=\"caption-attachment-3425\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3425 size-full\" src=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1.jpg\" alt=\"Play&amp;Work-arrangement-Nowy-Styl-Group-1\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1.jpg 1200w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1-300x169.jpg 300w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1-768x432.jpg 768w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1-1024x576.jpg 1024w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1-665x374.jpg 665w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-m-cta-t1-462x260.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><figcaption id=\"caption-attachment-3425\" class=\"wp-caption-text\">Nowy-Styl &#8211; Play&amp;Work<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h2 id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-WiestehtderComputerrichtig?\"><span class=\"fliesstext subheading\" style=\"font-family: 'Roboto Slab', sans-serif; font-size: 20px; line-height: 24px; font-weight: 400; margin-top: 40px; text-transform: none; margin-left: 12.5%;\">Wie steht der Computer richtig?<\/span><\/h2>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Stellen Sie den Computer so hin, dass Ihr Blick leicht gesenkt auf den Bildschirm f\u00e4llt. Der Abstand zwischen Bildschirm und Kopf sollte mindestens 50 cm betragen, besser noch 70. Bei einem Laptop k\u00f6nnen Sie Abhilfe schaffen, indem Sie ein zus\u00e4tzliches Keyboard vor die Tastatur stellen.<\/span><\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">\u00dcbrigens: . Haben Sie einen kleinen 15-Zoll-Laptop? Vergessen Sie das zweite Keyboard und verbinden Sie ihn stattdessen mit einem externen 24-Zoll-Monitor, den Sie 70 cm von sich selbst entfernt aufstellen.<\/span><\/p>\n<p>&nbsp;<\/p>\n<div class=\"rbs_shortcode\"><style type=\"text\/css\" scoped>.roboGalleryLoaderSpinner{\r\n\tmargin: 50px auto;\r\n\twidth: 50px;\r\n\theight: 40px;\r\n\ttext-align: center;\r\n\tfont-size: 10px;\r\n}\r\n.roboGalleryLoaderSpinner > div{\r\n  background-color: #333;\r\n  height: 100%;\r\n  width: 6px;\r\n  display: inline-block;\r\n\r\n  -webkit-animation: roboGalleryLoader-stretchdelay 1.2s infinite ease-in-out;\r\n  animation: roboGalleryLoader-stretchdelay 1.2s infinite ease-in-out;\r\n}\r\n.roboGalleryLoaderSpinner .roboGalleryLoaderRect2 {\r\n  -webkit-animation-delay: -1.1s;\r\n  animation-delay: -1.1s;\r\n}\r\n.roboGalleryLoaderSpinner .roboGalleryLoaderRect3 {\r\n  -webkit-animation-delay: -1.0s;\r\n  animation-delay: -1.0s;\r\n}\r\n.roboGalleryLoaderSpinner .roboGalleryLoaderRect4 {\r\n  -webkit-animation-delay: -0.9s;\r\n  animation-delay: -0.9s;\r\n}\r\n.roboGalleryLoaderSpinner .roboGalleryLoaderRect5 {\r\n  -webkit-animation-delay: -0.8s;\r\n  animation-delay: -0.8s;\r\n}\r\n@-webkit-keyframes roboGalleryLoader-stretchdelay {\r\n  0%, 40%, 100% { -webkit-transform: scaleY(0.4) }  \r\n  20% { -webkit-transform: scaleY(1.0) }\r\n}\r\n@keyframes roboGalleryLoader-stretchdelay {\r\n  0%, 40%, 100% { \r\n    transform: scaleY(0.4);\r\n    -webkit-transform: scaleY(0.4);\r\n  }  20% { \r\n    transform: scaleY(1.0);\r\n    -webkit-transform: scaleY(1.0);\r\n  }\r\n}<\/style><div id=\"robo_gallery_loading_rbs_gallery_6a049511a468a\" class=\"roboGalleryLoaderSpinner\"><div class=\"roboGalleryLoaderRect1\"><\/div> <div class=\"roboGalleryLoaderRect2\"><\/div> <div class=\"roboGalleryLoaderRect3\"><\/div> <div class=\"roboGalleryLoaderRect4\"><\/div> <div class=\"roboGalleryLoaderRect5\"><\/div><\/div><div id=\"robo_gallery_main_block_rbs_gallery_6a049511a468a\" style=\"width:100%;  display: none;\"><div>           <\/div><div id=\"rbs_gallery_6a049511a468a\" data-options=\"rbs_gallery_6a049511a468a\" style=\"width:100%;\" class=\"robo_gallery\"><div class=\"rbs-img category3416 \" ><div class=\"rbs-img-image  rbs-lightbox\"   ><div data-thumbnail=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/4ME-2ME-chairs-Nowy-Styl-Group-2.jpg\" title=\"4ME &amp; 2ME-chairs-Nowy-Styl-Group-2\" data-width=\"1201\" data-height=\"1800\" ><\/div><div data-popup=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/4ME-2ME-chairs-Nowy-Styl-Group-2.jpg\" data-alt=\"4ME &amp; 2ME-chairs-Nowy-Styl-Group-2\" title=\"4ME &amp; 2ME-chairs-Nowy-Styl-Group-2\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsTitle \">4ME & 2ME-chairs-Nowy-Styl-Group-2<\/div><\/div><\/div><\/div><div class=\"rbs-img category3416 \" ><div class=\"rbs-img-image  rbs-lightbox\"   ><div data-thumbnail=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/PlayWork-arrangement-Nowy-Styl-Group-2-1.jpg\" title=\"Play&amp;Work-arrangement-Nowy-Styl-Group-2\" data-width=\"1201\" data-height=\"1800\" ><\/div><div data-popup=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/PlayWork-arrangement-Nowy-Styl-Group-2-1.jpg\" data-alt=\"Play&amp;Work-arrangement-Nowy-Styl-Group-2\" title=\"Play&amp;Work-arrangement-Nowy-Styl-Group-2\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsTitle \">Play&Work-arrangement-Nowy-Styl-Group-2<\/div><\/div><\/div><\/div><div class=\"rbs-img category3416 \" ><div class=\"rbs-img-image  rbs-lightbox\"   ><div data-thumbnail=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/PlayWork-arrangement-Nowy-Styl-Group-3-1.jpg\" title=\"Play&amp;Work-arrangement-Nowy-Styl-Group-3\" data-width=\"1201\" data-height=\"1800\" ><\/div><div data-popup=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/PlayWork-arrangement-Nowy-Styl-Group-3-1.jpg\" data-alt=\"Play&amp;Work-arrangement-Nowy-Styl-Group-3\" title=\"Play&amp;Work-arrangement-Nowy-Styl-Group-3\" ><\/div><div class=\"thumbnail-overlay\"><div class=\"rbsTitle \">Play&Work-arrangement-Nowy-Styl-Group-3<\/div><\/div><\/div><\/div><\/div><div>           <\/div><\/div><script>var rbs_gallery_6a049511a468a = {\"filterContainer\": \"#rbs_gallery_6a049511a468afilter\", \"loadingContainer\": \"#robo_gallery_loading_rbs_gallery_6a049511a468a\", \"mainContainer\": \"#robo_gallery_main_block_rbs_gallery_6a049511a468a\", \"touch\": 1, \"lightboxOptions\": { gallery: { enabled: true, tCounter: \"%curr% of %total%\" } }, \"columns\": 3, \"columnWidth\": \"auto\", \"resolutions\": [{\"columnWidth\": 300 , \"maxWidth\": 960} , {\"columnWidth\": 300 , \"maxWidth\": 650} , {\"columnWidth\": 300 , \"maxWidth\": 450}], \"overlayEffect\": \"direction-aware-fade\", \"boxesToLoadStart\": 12, \"boxesToLoad\": 8, \"lazyLoad\": true, \"waitUntilThumbLoads\": true, \"waitForAllThumbsNoMatterWhat\": false, \"deepLinking\": false, \"LoadingWord\": \"Loading...\", \"loadMoreWord\": \"Load More\", \"loadMoreClass\": \"button-border-caution \", \"noMoreEntriesWord\": \"No More Entries\", \"horizontalSpaceBetweenBoxes\": 15, \"verticalSpaceBetweenBoxes\": 15}, rbs_gallery_6a049511a468a_css = \"body .mfp-ready.mfp-bg{background-color: rgba(11, 11, 11, 0.8);}#rbs_gallery_6a049511a468a .rbs-img-container{ -webkit-border-radius: 0px; -moz-border-radius: 0px; border-radius: 0px;-webkit-box-shadow:0px 5px 7px rgba(34, 25, 25, 0.4) ;-moz-box-shadow: \t0px 5px 7px rgba(34, 25, 25, 0.4) ;-o-box-shadow: \t0px 5px 7px rgba(34, 25, 25, 0.4) ;-ms-box-shadow: \t0px 5px 7px rgba(34, 25, 25, 0.4) ;box-shadow: \t\t0px 5px 7px rgba(34, 25, 25, 0.4) ;}#rbs_gallery_6a049511a468a .rbsTitle{ font-size:12px; line-height:100%; color:rgb(255, 255, 255); font-weight:bold;}#rbs_gallery_6a049511a468a .rbsTitle:hover{color:rgb(255, 255, 255);}#rbs_gallery_6a049511a468a .thumbnail-overlay{background:rgba(7, 7, 7, 0.5);}#rbs_gallery_6a049511a468a .image-with-dimensions{background-color: rgb(255, 255, 255);}body .mfp-title, body .mfp-counter{color: rgb(243, 243, 243);}\",roboGalleryDelay = 0; head = document.head || document.getElementsByTagName(\"head\")[0], style = document.createElement(\"style\"); style.type = \"text\/css\"; if (style.styleSheet) style.styleSheet.cssText = rbs_gallery_6a049511a468a_css; \telse  style.appendChild(document.createTextNode(rbs_gallery_6a049511a468a_css)); head.appendChild(style);<\/script><\/div>\n<p>&nbsp;<\/p>\n<h2 id=\"id-(magazin)DasergonomischeB\u00fcrozuHause-DasArbeitszimmerrichtiggestalten\"><span class=\"fliesstext subheading\" style=\"font-family: 'Roboto Slab', sans-serif; font-size: 20px; line-height: 24px; font-weight: 400; margin-top: 40px; text-transform: none; margin-left: 12.5%;\">Das Arbeitszimmer richtig gestalten<\/span><\/h2>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Haben Sie die passenden M\u00f6bel gefunden, widmen Sie sich der optimalen Einrichtung Ihres Arbeitszimmers. Ganz wichtig f\u00fcr das ergonomische B\u00fcro sind die richtigen Lichtverh\u00e4ltnisse. Tageslicht ist ein Muss, doch die direkte Sonne sollte Sie nicht blenden oder direkt auf den Bildschirm fallen. Beides kann zu Kopfschmerzen f\u00fchren. Stellen Sie den Schreibtisch am besten so auf, dass das Licht seitlich einf\u00e4llt oder von vorne kommt. So k\u00f6nnen sich Ihre Augen ab und zu ausruhen, indem Sie den Blick ins Freie schweifen lassen.<\/span><\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">An tr\u00fcben Tagen und im Winter ist\u00a0<a class=\"external-link\" href=\"https:\/\/www.zurbrueggen.de\/magazin\/lichttechnik-richtig-einsetzen-aesthetisch-und-effizient\/\" rel=\"nofollow\">optimale Lichttechnik<\/a>\u00a0gefragt. Am besten erhellen Sie das Zimmer indirekt mit sch\u00f6nen Wandleuchten oder Deckenflutern. Das kalte Neonlicht Ihrer Firma m\u00fcssen Sie sich zu Hause nicht antun. Denken Sie auch an eine Schreibtischlampe, um den direkten Arbeitsbereich zu erhellen.<\/span><\/p>\n<p><span class=\"fliesstext\" style=\"font-family: Roboto, sans-serif; font-size: 16px; line-height: 24px; font-weight: 400;\">Ein gutes Raumklima h\u00e4lt Sie bei l\u00e4ngerem Arbeiten frisch. Achten Sie darauf, dass die Luftfeuchtigkeit nicht unter 40 Prozent sinkt: Stellen Sie ein bis zwei Gr\u00fcnpflanzen mit gro\u00dfen Bl\u00e4ttern in Schreibtischn\u00e4he und l\u00fcften Sie mehrmals am Tag gut durch.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3420\" aria-describedby=\"caption-attachment-3420\" style=\"width: 1200px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.zurbrueggen.de\/shop\/cantus-komplett-buero-juno-1869\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3420 size-full\" src=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05.jpg\" alt=\"office-line-cantus\" width=\"1200\" height=\"675\" srcset=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05.jpg 1200w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05-300x169.jpg 300w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05-768x432.jpg 768w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05-1024x576.jpg 1024w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05-665x374.jpg 665w, https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-office-line-cantus-0164716-m-05-462x260.jpg 462w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><figcaption id=\"caption-attachment-3420\" class=\"wp-caption-text\">cantus &#8211; Komplett-B\u00fcro JUNO<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch arbeiten, sind Ihnen R\u00fccken- und Nackenschmerzen wahrscheinlich vertraut. Mit ergonomischen B\u00fcrom\u00f6beln wirken Sie dem entgegen und nutzen den Raum mithilfe praktischer Funktionen auch noch optimal aus. Dank der gro\u00dfen Auswahl an M\u00f6beln und mit den folgenden [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":3427,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,45,26],"tags":[],"class_list":["post-3400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alle-artikel","category-trend-einrichtung","category-wohnwelten"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Das ergonomische B\u00fcro zu Hause &#8211; Zurbr\u00fcggen magazin<\/title>\n<meta name=\"description\" content=\"Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch - Ergonomisch Ergonomie f\u00fcr Ihr Heimb\u00fcro: lesen Sie jetzt, wie Sie Ihren Arbeitsplatz ergonomisch und trotzdem stylisch einrichten. Unser Magazin gibt hilreiche Tipps!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ergonomie f\u00fcrs Heimb\u00fcro\" \/>\n<meta property=\"og:description\" content=\"Praktische Tipps f\u00fcr ein ergonomisch und trotzdem stylisch eingerichtetes B\u00fcro zu Hause.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/\" \/>\n<meta property=\"og:site_name\" content=\"Zurbr\u00fcggen magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/zurbrueggen\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-11T12:24:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-12T13:15:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Linda Wolfgart\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/\"},\"author\":{\"name\":\"Linda Wolfgart\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#\\\/schema\\\/person\\\/07170b1da6f7876ac78e450b9a3ed3d6\"},\"headline\":\"Das ergonomische B\u00fcro zu Hause\",\"datePublished\":\"2018-09-11T12:24:28+00:00\",\"dateModified\":\"2018-09-12T13:15:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/\"},\"wordCount\":860,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg\",\"articleSection\":[\"Alle Artikel\",\"trend\",\"Wohnwelten\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/\",\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/\",\"name\":\"Das ergonomische B\u00fcro zu Hause &#8211; Zurbr\u00fcggen magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg\",\"datePublished\":\"2018-09-11T12:24:28+00:00\",\"dateModified\":\"2018-09-12T13:15:11+00:00\",\"description\":\"Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch - Ergonomisch Ergonomie f\u00fcr Ihr Heimb\u00fcro: lesen Sie jetzt, wie Sie Ihren Arbeitsplatz ergonomisch und trotzdem stylisch einrichten. Unser Magazin gibt hilreiche Tipps!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg\",\"width\":1200,\"height\":675,\"caption\":\"Max Berger -Office l100\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/das-ergonomische-buero-zu-hause\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Das ergonomische B\u00fcro zu Hause\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/\",\"name\":\"Zurbr\u00fcggen magazin\",\"description\":\"DESIGN \u2022 STYLE \u2022 LIVING\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#organization\",\"name\":\"Zurbr\u00fcggen Wohn-Zentrum GmbH\",\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo_zurbrueggen.png\",\"contentUrl\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo_zurbrueggen.png\",\"width\":400,\"height\":107,\"caption\":\"Zurbr\u00fcggen Wohn-Zentrum GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/zurbrueggen\",\"https:\\\/\\\/x.com\\\/Zurbrueggen\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/#\\\/schema\\\/person\\\/07170b1da6f7876ac78e450b9a3ed3d6\",\"name\":\"Linda Wolfgart\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g\",\"caption\":\"Linda Wolfgart\"},\"url\":\"https:\\\/\\\/www.zurbrueggen.de\\\/magazin\\\/author\\\/l_junowicz\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Das ergonomische B\u00fcro zu Hause &#8211; Zurbr\u00fcggen magazin","description":"Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch - Ergonomisch Ergonomie f\u00fcr Ihr Heimb\u00fcro: lesen Sie jetzt, wie Sie Ihren Arbeitsplatz ergonomisch und trotzdem stylisch einrichten. Unser Magazin gibt hilreiche Tipps!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/","og_locale":"de_DE","og_type":"article","og_title":"Ergonomie f\u00fcrs Heimb\u00fcro","og_description":"Praktische Tipps f\u00fcr ein ergonomisch und trotzdem stylisch eingerichtetes B\u00fcro zu Hause.","og_url":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/","og_site_name":"Zurbr\u00fcggen magazin","article_publisher":"https:\/\/facebook.com\/zurbrueggen","article_published_time":"2018-09-11T12:24:28+00:00","article_modified_time":"2018-09-12T13:15:11+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg","type":"image\/jpeg"}],"author":"Linda Wolfgart","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#article","isPartOf":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/"},"author":{"name":"Linda Wolfgart","@id":"https:\/\/www.zurbrueggen.de\/magazin\/#\/schema\/person\/07170b1da6f7876ac78e450b9a3ed3d6"},"headline":"Das ergonomische B\u00fcro zu Hause","datePublished":"2018-09-11T12:24:28+00:00","dateModified":"2018-09-12T13:15:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/"},"wordCount":860,"commentCount":0,"publisher":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/#organization"},"image":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg","articleSection":["Alle Artikel","trend","Wohnwelten"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/","url":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/","name":"Das ergonomische B\u00fcro zu Hause &#8211; Zurbr\u00fcggen magazin","isPartOf":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#primaryimage"},"image":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg","datePublished":"2018-09-11T12:24:28+00:00","dateModified":"2018-09-12T13:15:11+00:00","description":"Mit geeigneten B\u00fcrom\u00f6beln den Arbeitsplatz ergonomisch gestalten:\u00a0Ganz gleich, ob zu Hause oder im Unternehmen: Wenn Sie regelm\u00e4\u00dfig am Schreibtisch - Ergonomisch Ergonomie f\u00fcr Ihr Heimb\u00fcro: lesen Sie jetzt, wie Sie Ihren Arbeitsplatz ergonomisch und trotzdem stylisch einrichten. Unser Magazin gibt hilreiche Tipps!","breadcrumb":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#primaryimage","url":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg","contentUrl":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2018\/09\/magazin-max-berger-living-office-l100-0926019-cta-m-01.jpg","width":1200,"height":675,"caption":"Max Berger -Office l100"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zurbrueggen.de\/magazin\/das-ergonomische-buero-zu-hause\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.zurbrueggen.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Das ergonomische B\u00fcro zu Hause"}]},{"@type":"WebSite","@id":"https:\/\/www.zurbrueggen.de\/magazin\/#website","url":"https:\/\/www.zurbrueggen.de\/magazin\/","name":"Zurbr\u00fcggen magazin","description":"DESIGN \u2022 STYLE \u2022 LIVING","publisher":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zurbrueggen.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.zurbrueggen.de\/magazin\/#organization","name":"Zurbr\u00fcggen Wohn-Zentrum GmbH","url":"https:\/\/www.zurbrueggen.de\/magazin\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zurbrueggen.de\/magazin\/#\/schema\/logo\/image\/","url":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2016\/07\/logo_zurbrueggen.png","contentUrl":"https:\/\/www.zurbrueggen.de\/magazin\/wp-content\/uploads\/2016\/07\/logo_zurbrueggen.png","width":400,"height":107,"caption":"Zurbr\u00fcggen Wohn-Zentrum GmbH"},"image":{"@id":"https:\/\/www.zurbrueggen.de\/magazin\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/zurbrueggen","https:\/\/x.com\/Zurbrueggen"]},{"@type":"Person","@id":"https:\/\/www.zurbrueggen.de\/magazin\/#\/schema\/person\/07170b1da6f7876ac78e450b9a3ed3d6","name":"Linda Wolfgart","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f84173980fbd4382d8c0ae77c07dbf27a65219dbdadb5b039dab209120bb5c55?s=96&d=mm&r=g","caption":"Linda Wolfgart"},"url":"https:\/\/www.zurbrueggen.de\/magazin\/author\/l_junowicz\/"}]}},"_links":{"self":[{"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/posts\/3400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/comments?post=3400"}],"version-history":[{"count":14,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/posts\/3400\/revisions"}],"predecessor-version":[{"id":3435,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/posts\/3400\/revisions\/3435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/media\/3427"}],"wp:attachment":[{"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/media?parent=3400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/categories?post=3400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zurbrueggen.de\/magazin\/wp-json\/wp\/v2\/tags?post=3400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}